{"id":193391,"date":"2018-06-17T14:50:26","date_gmt":"2018-06-17T20:50:26","guid":{"rendered":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/?post_type=post-espectaculos&#038;p=193391"},"modified":"2018-06-17T14:50:26","modified_gmt":"2018-06-17T20:50:26","slug":"velocidad","status":"publish","type":"post-espectaculos","link":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad","title":{"rendered":"La ley para regular el l\u00edmite de velocidad esta totalmente olvidada"},"content":{"rendered":"<p>De acuerdo a las estad\u00edsticas de enero a la fecha se han suscitado m\u00e1s de 218 accidentes viales en toda la rep\u00fablica, pero de estos, 76 fueron ocasionados por transporte pesado y seis hechos en la Ruta Interamericana, jurisdicci\u00f3n de Mixco. Es por ello que nos hacemos la interrogante \u00bfCuantas muertes m\u00e1s tienen que ocurrir para que se implemente la ley de l\u00edmite de velocidad en Guatemala?<\/p>\n\n<p><span style=\"font-weight: 400;\">Seg\u00fan datos del INE Instituto Nacional de Estad\u00edstica en el a\u00f1o 2017 hubo 1,480 muertes y 7,145 heridos por accidentes viales en todo el pa\u00eds.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El 27 de Octubre del 2016 se public\u00f3 en el Diario de Centroam\u00e9rica el decreto de <em><strong>ley 45-2016<\/strong><\/em> por el Congreso de la Rep\u00fablica donde se indicaba <\/span><i><span style=\"font-weight: 400;\">\u201cque debido a los percances ocurridos en los \u00faltimos meses, ocasionados por veh\u00edculos de transporte colectivo y de carga en todo el territorio nacional, los cuales han enlutado a cientos de familias guatemaltecas, se evidencia la falta de control sobre veh\u00edculos de transporte colectivo de pasajeros y de carga, por lo que se hace necesaria la aprobaci\u00f3n de leyes que contribuyan al fortalecimiento de la seguridad vial<\/span><\/i><span style=\"font-weight: 400;\">\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En su Art\u00edculo 2 especifica el procedimiento para la implementaci\u00f3n del Sistema Limitador de v<\/span><span style=\"font-weight: 400;\">elocidad. <\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u201cPara efectos de la aplicaci\u00f3n de la presente Ley, se establece la obligatoriedad de los propietarios y\/o representantes legales de empresas de transportes a efectuar a su costa una modificaci\u00f3n mec\u00e1nica en la bomba de inyecci\u00f3n de los veh\u00edculos automotores que se dedican al transporte colectivo de pasajeros y de carga, ya sean accionados por mecanismos mec\u00e1nicos y\/o electr\u00f3nicos, para que los mismo desarrollen un l\u00edmite m\u00e1ximo de velocidad de hasta ochenta (80) kil\u00f3metros por hora.<\/span><\/i><\/p>\n<blockquote><p><i><span style=\"font-weight: 400;\">\u201dTras casi 2 a\u00f1os de haber decretado la ley a\u00fan no se ha implementado y la tragedia de los accidentes por alta velocidad contin\u00faa.<\/span><\/i><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<div id=\"carousel-193391-3363083657\" \n                    class=\"carousel slide carousel-fade\"  \n                    data-ride=\"carousel\" \n                    data-keyboard=\"false\" >\n\t\t\t\t\t\t<div class=\"carousel-inner\" role=\"listbox\"><div class=\"item  active\">\n\t\t\t\t\t<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.56.51-p.m..png\" \n\t\t\t\t\tclass=\"foto\" style=\"background-image:url(https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.56.51-p.m..png?quality=82&w=288);\" \n\t\t\t\t\tdata-toggle=\"lightbox\" \n\t\t\t\t\tdata-type=\"image\" \n\t\t\t\t\tdata-gallery=\"galeria193391-3363083657\"><\/a>\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pie-carousel\">Galer\u00eda: Foto 1 de 4<\/span>\n\t\t\t\t\t<\/div><div class=\"item  \">\n\t\t\t\t\t<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.56.43-p.m..png\" \n\t\t\t\t\tclass=\"foto\" style=\"background-image:url(https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.56.43-p.m..png?quality=82&w=288);\" \n\t\t\t\t\tdata-toggle=\"lightbox\" \n\t\t\t\t\tdata-type=\"image\" \n\t\t\t\t\tdata-gallery=\"galeria193391-3363083657\"><\/a>\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pie-carousel\">Galer\u00eda: Foto 2 de 4<\/span>\n\t\t\t\t\t<\/div><div class=\"item  \">\n\t\t\t\t\t<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.56.37-p.m..png\" \n\t\t\t\t\tclass=\"foto\" style=\"background-image:url(https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.56.37-p.m..png?quality=82&w=286);\" \n\t\t\t\t\tdata-toggle=\"lightbox\" \n\t\t\t\t\tdata-type=\"image\" \n\t\t\t\t\tdata-gallery=\"galeria193391-3363083657\"><\/a>\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pie-carousel\">Galer\u00eda: Foto 3 de 4<\/span>\n\t\t\t\t\t<\/div><div class=\"item  \">\n\t\t\t\t\t<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.56.28-p.m..png\" \n\t\t\t\t\tclass=\"foto\" style=\"background-image:url(https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.56.28-p.m..png?quality=82&w=287);\" \n\t\t\t\t\tdata-toggle=\"lightbox\" \n\t\t\t\t\tdata-type=\"image\" \n\t\t\t\t\tdata-gallery=\"galeria193391-3363083657\"><\/a>\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pie-carousel\">Galer\u00eda: Foto 4 de 4<\/span>\n\t\t\t\t\t<\/div><\/div><div>\n\t\t\t\t<a class=\"left carousel-control\" href=\"#carousel-193391-3363083657\" role=\"button\" data-slide=\"prev\">\n\t\t\t        <i class=\"icon-arrow-left glyphicon glyphicon-chevron-right\"><\/i>\n\t\t\t        <span class=\"sr-only\">Previous<\/span><\/a>\n\t\t        <a class=\"right carousel-control\" href=\"#carousel-193391-3363083657\" role=\"button\" data-slide=\"next\">\n\t\t\t        <i class=\"icon-arrow-right glyphicon glyphicon-chevron-left\"><\/i>\n\t\t\t        <span class=\"sr-only\">Next<\/span><\/a>\n\t\t        <\/div>\n\t\t        <\/div>\n<h3>Tecnolog\u00eda en Guatemala que ayudar\u00eda<\/h3>\n<p><span style=\"font-weight: 400;\">Existen equipos con la tecnolog\u00eda para limitar cualquier tipo de veh\u00edculo (pick up, camioneta, cami\u00f3n, cabezal\u2026) con bomba mec\u00e1nica o electr\u00f3nica ya disponibles en Guatemala para poder implementar la ley de inmediato. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hablamos con el <a href=\"https:\/\/www.facebook.com\/autowinway\/\" target=\"_blank\" rel=\"noopener\">Ing. Julio Ira\u00f1eta<\/a> sobre estos equipos para poder implementar en el pa\u00eds esta ley que tantas vidas salvar\u00eda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cEstos equipos se usan desde hace varios a\u00f1os en USA, Europa y Asia. \u00a0Emplean tecnolog\u00eda via satelital para evitar la intromisi\u00f3n en el sistema original del veh\u00edculo. Son por lo tanto para todo tipo de veh\u00edculo, marca y sistema de inyecci\u00f3n di\u00e9sel mec\u00e1nica y electr\u00f3nica.\u201d \u00a0afirm\u00f3 Ira\u00f1eta.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.facebook.com\/autowinway\/\" target=\"_blank\" rel=\"noopener\">El sistema<\/a> tiene una Alarma sonora previo a que el equipo intervenga limitando la velocidad del veh\u00edculo para advertir al piloto.\u00a0<\/span><span style=\"font-weight: 400;\">Desde el punto de vista de la seguridad es excelente y tambi\u00e9n para las empresas supone un beneficio en el ahorro de combustible y gastos de flota como llantas o frenos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<div id=\"carousel-193391-2391416955\" \n                    class=\"carousel slide carousel-fade\"  \n                    data-ride=\"carousel\" \n                    data-keyboard=\"false\" >\n\t\t\t\t\t\t<div class=\"carousel-inner\" role=\"listbox\"><div class=\"item  active\">\n\t\t\t\t\t<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.55.07-p.m..png\" \n\t\t\t\t\tclass=\"foto\" style=\"background-image:url(https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.55.07-p.m..png?quality=82&w=209);\" \n\t\t\t\t\tdata-toggle=\"lightbox\" \n\t\t\t\t\tdata-type=\"image\" \n\t\t\t\t\tdata-gallery=\"galeria193391-2391416955\"><\/a>\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pie-carousel\">Galer\u00eda: Foto 1 de 3<\/span>\n\t\t\t\t\t<\/div><div class=\"item  \">\n\t\t\t\t\t<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.55.00-p.m..png\" \n\t\t\t\t\tclass=\"foto\" style=\"background-image:url(https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.55.00-p.m..png?quality=82&w=494);\" \n\t\t\t\t\tdata-toggle=\"lightbox\" \n\t\t\t\t\tdata-type=\"image\" \n\t\t\t\t\tdata-gallery=\"galeria193391-2391416955\"><\/a>\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pie-carousel\">Galer\u00eda: Foto 2 de 3<\/span>\n\t\t\t\t\t<\/div><div class=\"item  \">\n\t\t\t\t\t<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.54.49-p.m..png\" \n\t\t\t\t\tclass=\"foto\" style=\"background-image:url(https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-1.54.49-p.m..png?quality=82&w=470);\" \n\t\t\t\t\tdata-toggle=\"lightbox\" \n\t\t\t\t\tdata-type=\"image\" \n\t\t\t\t\tdata-gallery=\"galeria193391-2391416955\"><\/a>\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pie-carousel\">Galer\u00eda: Foto 3 de 3<\/span>\n\t\t\t\t\t<\/div><\/div><div>\n\t\t\t\t<a class=\"left carousel-control\" href=\"#carousel-193391-2391416955\" role=\"button\" data-slide=\"prev\">\n\t\t\t        <i class=\"icon-arrow-left glyphicon glyphicon-chevron-right\"><\/i>\n\t\t\t        <span class=\"sr-only\">Previous<\/span><\/a>\n\t\t        <a class=\"right carousel-control\" href=\"#carousel-193391-2391416955\" role=\"button\" data-slide=\"next\">\n\t\t\t        <i class=\"icon-arrow-right glyphicon glyphicon-chevron-left\"><\/i>\n\t\t\t        <span class=\"sr-only\">Next<\/span><\/a>\n\t\t        <\/div>\n\t\t        <\/div>\n<p>Vea Tambi\u00e9n;:\u00a0<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/accesorios\/\" target=\"_blank\" rel=\"noopener\">Lo que necesita saber antes de comprar accesorios para su veh\u00edculo y evitar as\u00ed accidentes<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El exceso de velocidad es una de las principales causas de accidentes viales, pero existe una tecnolog\u00eda ya en Guatemala que puede ayudar a prevenir fatales accidentes. <\/p>\n","protected":false},"author":218,"featured_media":193399,"template":"","etiqueta":[25363,25364,24764],"class_list":["post-193391","post-espectaculos","type-post-espectaculos","status-publish","has-post-thumbnail","hentry","categoria-post-espectaculos-entretenimiento","etiqueta-limite-de-velocidad","etiqueta-prevenir-accidentes","etiqueta-winway"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La ley para regular el l\u00edmite de velocidad esta totalmente olvidada<\/title>\n<meta name=\"description\" content=\"El exceso de velocidad es una de las principales causas de accidentes viales, pero existe una tecnolog\u00eda ya en Guatemala que puede ayudar a prevenir fatales accidentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ley para regular el l\u00edmite de velocidad esta totalmente olvidada\" \/>\n<meta property=\"og:description\" content=\"El exceso de velocidad es una de las principales causas de accidentes viales, pero existe una tecnolog\u00eda ya en Guatemala que puede ayudar a prevenir fatales accidentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad\" \/>\n<meta property=\"og:site_name\" content=\"Guatevision\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-2.47.21-p.m..png?quality=82\" \/>\n\t<meta property=\"og:image:width\" content=\"1360\" \/>\n\t<meta property=\"og:image:height\" content=\"758\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad\",\"name\":\"La ley para regular el l\u00edmite de velocidad esta totalmente olvidada\",\"isPartOf\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad#primaryimage\"},\"image\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-2.47.21-p.m..png\",\"datePublished\":\"2018-06-17T20:50:26+00:00\",\"dateModified\":\"2018-06-17T20:50:26+00:00\",\"description\":\"El exceso de velocidad es una de las principales causas de accidentes viales, pero existe una tecnolog\u00eda ya en Guatemala que puede ayudar a prevenir fatales accidentes.\",\"inLanguage\":\"es-GT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-GT\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad#primaryimage\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-2.47.21-p.m..png\",\"contentUrl\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-2.47.21-p.m..png\",\"width\":1360,\"height\":758},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/\",\"name\":\"Guatevision\",\"description\":\"\u00a1Enciende Lo Bueno!\",\"publisher\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-GT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization\",\"name\":\"Guatevision\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-GT\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png\",\"contentUrl\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png\",\"width\":1000,\"height\":600,\"caption\":\"Guatevision\"},\"image\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La ley para regular el l\u00edmite de velocidad esta totalmente olvidada","description":"El exceso de velocidad es una de las principales causas de accidentes viales, pero existe una tecnolog\u00eda ya en Guatemala que puede ayudar a prevenir fatales accidentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad","og_locale":"es_ES","og_type":"article","og_title":"La ley para regular el l\u00edmite de velocidad esta totalmente olvidada","og_description":"El exceso de velocidad es una de las principales causas de accidentes viales, pero existe una tecnolog\u00eda ya en Guatemala que puede ayudar a prevenir fatales accidentes.","og_url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad","og_site_name":"Guatevision","og_image":[{"width":1360,"height":758,"url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-2.47.21-p.m..png?quality=82","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad","name":"La ley para regular el l\u00edmite de velocidad esta totalmente olvidada","isPartOf":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad#primaryimage"},"image":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad#primaryimage"},"thumbnailUrl":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-2.47.21-p.m..png","datePublished":"2018-06-17T20:50:26+00:00","dateModified":"2018-06-17T20:50:26+00:00","description":"El exceso de velocidad es una de las principales causas de accidentes viales, pero existe una tecnolog\u00eda ya en Guatemala que puede ayudar a prevenir fatales accidentes.","inLanguage":"es-GT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad"]}]},{"@type":"ImageObject","inLanguage":"es-GT","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculos\/entretenimiento\/velocidad#primaryimage","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-2.47.21-p.m..png","contentUrl":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2018\/06\/Captura-de-pantalla-2018-06-17-a-las-2.47.21-p.m..png","width":1360,"height":758},{"@type":"WebSite","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/","name":"Guatevision","description":"\u00a1Enciende Lo Bueno!","publisher":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-GT"},{"@type":"Organization","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization","name":"Guatevision","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/","logo":{"@type":"ImageObject","inLanguage":"es-GT","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png","contentUrl":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png","width":1000,"height":600,"caption":"Guatevision"},"image":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/post-espectaculos\/193391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/post-espectaculos"}],"about":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/types\/post-espectaculos"}],"author":[{"embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/users\/218"}],"version-history":[{"count":0,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/post-espectaculos\/193391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/media\/193399"}],"wp:attachment":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/media?parent=193391"}],"wp:term":[{"taxonomy":"etiqueta","embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/etiqueta?post=193391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}