{"id":279318,"date":"2019-06-08T21:14:43","date_gmt":"2019-06-09T03:14:43","guid":{"rendered":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/?post_type=post-noticias&#038;p=279318"},"modified":"2019-06-13T19:02:42","modified_gmt":"2019-06-14T01:02:42","slug":"fiscal-delitos-electorales-cargo","status":"publish","type":"post-noticias","link":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo","title":{"rendered":"Fiscal de delitos electorales deja el cargo temporalmente"},"content":{"rendered":"<p><span data-contrast=\"auto\">Oscar\u00a0<\/span><span data-contrast=\"auto\">Schaad<\/span><span data-contrast=\"auto\">, fiscal de delitos electorales dej\u00f3 el cargo de manera temporal, as\u00ed lo confirm\u00f3 el Ministerio P\u00fablico. <\/span><\/p>\n\n<p><span data-contrast=\"auto\">El encargado de la investigaci\u00f3n de casos de financiamiento electoral tom\u00f3 tres d\u00edas de vacaciones, 8,9 y 10 de junio, estando en este per\u00edodo solicit\u00f3 una licencia con goce de salario de tres meses que iniciar\u00e1n el pr\u00f3ximo 11 de junio.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Julia Barrera, vocera del MP, explic\u00f3 que la licencia fue otorgada <\/span><span data-contrast=\"auto\">de\u00a0<\/span><span data-contrast=\"auto\">conformidad a lo establecido por el pacto colectivo de la instituci\u00f3n. Agreg\u00f3 que el agente fiscal Rafael\u00a0<\/span><span data-contrast=\"auto\">Curruchiche<\/span><span data-contrast=\"auto\">\u00a0estar\u00e1 a cargo del despacho de la fiscal\u00eda mientras\u00a0<\/span><span data-contrast=\"auto\">Schaad<\/span><span data-contrast=\"auto\">\u00a0retorna.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u201c<\/span><span data-contrast=\"auto\">La Fiscal\u00eda contra Delitos Electorales continua su labor con normalidad y est\u00e1 todo listo para el plan de acci\u00f3n del MP para el pr\u00f3ximo domingo<\/span><span data-contrast=\"auto\">\u201d, asegur\u00f3 Barrera. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Genera preocupaci\u00f3n\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Diferentes sectores han mostrado su preocupaci\u00f3n por las repentinas vacaciones de\u00a0<\/span><span data-contrast=\"auto\">Schaad<\/span><span data-contrast=\"auto\">, debido a que coinciden con las elecciones generales.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">El procurador de los Derechos Humanos, Augusto Jord\u00e1n Rodas, escribi\u00f3 en su cuenta de Twitter: \u201c<\/span><span data-contrast=\"auto\">A pocos d\u00edas de las\u00a0<\/span><a href=\"https:\/\/twitter.com\/hashtag\/EleccionesGenerales2019?src=hash\"><span data-contrast=\"none\">#<\/span><b><span data-contrast=\"none\">EleccionesGenerales2019<\/span><\/b><\/a><span data-contrast=\"auto\">\u00a0y en medio de denuncias de delitos electorales, llama poderosamente la atenci\u00f3n que el fiscal Oscar\u00a0<\/span><span data-contrast=\"auto\">Schaad<\/span><span data-contrast=\"auto\">\u00a0del\u00a0<\/span><a href=\"https:\/\/twitter.com\/MPguatemala\"><span data-contrast=\"none\">@<\/span><b><span data-contrast=\"none\">MPguatemala<\/span><\/b><\/a><span data-contrast=\"auto\">\u00a0solicite licencia. Me preocupa su seguridad, espero que esta situaci\u00f3n no sea producto de amenazas\u201d.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Mientras integrantes del Mirador Electoral aseguraron que es un riesgo para el proceso que a una semana de las elecciones quien est\u00e1 cargo de investigar y perseguir los delitos electorales se separe temporalmente de su cargo. \u201cExpresamos nuestra esperanza que esto sea solamente por el periodo de tiempo especificado y no sea consecuencia de ning\u00fan otro tipo de motivos subyacentes que amenacen la integridad f\u00edsica del fiscal\u00a0<\/span><span data-contrast=\"auto\">Schaad<\/span><span data-contrast=\"auto\">\u00a0ni limiten las funciones de la oficina a su cargo\u201d, expresaron en un comunicado.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>La diputada Nineth Montenegro de Encuentro por Guatemala tambi\u00e9n comparti\u00f3 su preocupaci\u00f3n. &#8220;\u00d3scar shaad, fue muy claro y dijo que se identific\u00f3 a varios supuestos exsoldados que amenazaron con boicotear el proceso electoral. Ruego antes deje un encargado para darle continuidad&#8221;, escribi\u00f3 en Twitter.<\/p>\n<div id=\"carousel-279318-1159504083\" \n                    class=\"carousel slide carousel-fade\"  \n                    data-ride=\"carousel\" \n                    data-keyboard=\"false\" >\n\t\t\t\t\t\t<div class=\"carousel-inner\" role=\"listbox\"><div class=\"item  active\">\n\t\t\t\t\t<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/Captura-de-pantalla-2019-06-08-a-las-16.37.40.png\" \n\t\t\t\t\tclass=\"foto\" style=\"background-image:url(https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/Captura-de-pantalla-2019-06-08-a-las-16.37.40.png?quality=82&w=240);\" \n\t\t\t\t\tdata-toggle=\"lightbox\" \n\t\t\t\t\tdata-type=\"image\" \n\t\t\t\t\tdata-gallery=\"galeria279318-1159504083\"><\/a>\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pie-carousel\">Galer\u00eda: Foto 1 de 3<\/span>\n\t\t\t\t\t<\/div><div class=\"item  \">\n\t\t\t\t\t<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/Captura-de-pantalla-2019-06-08-a-las-16.38.37.png\" \n\t\t\t\t\tclass=\"foto\" style=\"background-image:url(https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/Captura-de-pantalla-2019-06-08-a-las-16.38.37.png?quality=82&w=652);\" \n\t\t\t\t\tdata-toggle=\"lightbox\" \n\t\t\t\t\tdata-type=\"image\" \n\t\t\t\t\tdata-gallery=\"galeria279318-1159504083\"><\/a>\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pie-carousel\">Galer\u00eda: Foto 2 de 3<\/span>\n\t\t\t\t\t<\/div><div class=\"item  \">\n\t\t\t\t\t<a href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/Captura-de-pantalla-2019-06-08-a-las-16.38.52.png\" \n\t\t\t\t\tclass=\"foto\" style=\"background-image:url(https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/Captura-de-pantalla-2019-06-08-a-las-16.38.52.png?quality=82&w=517);\" \n\t\t\t\t\tdata-toggle=\"lightbox\" \n\t\t\t\t\tdata-type=\"image\" \n\t\t\t\t\tdata-gallery=\"galeria279318-1159504083\"><\/a>\n\t\t\t\t\t\n\t\t\t\t\t<span class=\"pie-carousel\">Galer\u00eda: Foto 3 de 3<\/span>\n\t\t\t\t\t<\/div><\/div><div>\n\t\t\t\t<a class=\"left carousel-control\" href=\"#carousel-279318-1159504083\" role=\"button\" data-slide=\"prev\">\n\t\t\t        <i class=\"icon-arrow-left glyphicon glyphicon-chevron-right\"><\/i>\n\t\t\t        <span class=\"sr-only\">Previous<\/span><\/a>\n\t\t        <a class=\"right carousel-control\" href=\"#carousel-279318-1159504083\" role=\"button\" data-slide=\"next\">\n\t\t\t        <i class=\"icon-arrow-right glyphicon glyphicon-chevron-left\"><\/i>\n\t\t\t        <span class=\"sr-only\">Next<\/span><\/a>\n\t\t        <\/div>\n\t\t        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>El fiscal encargado de investigar casos como financiamiento electoral de partidos pol\u00edticos estar\u00e1 fuera de labores hasta septiembre. <\/p>\n","protected":false},"author":104,"featured_media":279336,"template":"","etiqueta":[35678,22508,21525,27808,21190,27809,21384],"class_list":["post-279318","post-noticias","type-post-noticias","status-publish","has-post-thumbnail","hentry","categoria-post-noticias-nacional","etiqueta-decision-libre-2019","etiqueta-delitos-electorales","etiqueta-financiamiento-electoral-ilicito","etiqueta-fiscalia-de-delitos-electorales","etiqueta-mp","etiqueta-oscar-schaad","etiqueta-tse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal de delitos electorales deja el cargo temporalmente<\/title>\n<meta name=\"description\" content=\"El fiscal encargado de investigar casos como financiamiento electoral de partidos pol\u00edticos estar\u00e1 fuera de labores hasta septiembre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal de delitos electorales deja el cargo temporalmente\" \/>\n<meta property=\"og:description\" content=\"El fiscal encargado de investigar casos como financiamiento electoral de partidos pol\u00edticos estar\u00e1 fuera de labores hasta septiembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo\" \/>\n<meta property=\"og:site_name\" content=\"Guatevision\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-14T01:02:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/oscar-schaad-.jpg?quality=82\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo\",\"name\":\"Fiscal de delitos electorales deja el cargo temporalmente\",\"isPartOf\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo#primaryimage\"},\"image\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/oscar-schaad-.jpg\",\"datePublished\":\"2019-06-09T03:14:43+00:00\",\"dateModified\":\"2019-06-14T01:02:42+00:00\",\"description\":\"El fiscal encargado de investigar casos como financiamiento electoral de partidos pol\u00edticos estar\u00e1 fuera de labores hasta septiembre.\",\"inLanguage\":\"es-GT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-GT\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo#primaryimage\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/oscar-schaad-.jpg\",\"contentUrl\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/oscar-schaad-.jpg\",\"width\":760,\"height\":430,\"caption\":\"Oscar Schaad, fiscal delitos electorales\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/\",\"name\":\"Guatevision\",\"description\":\"\u00a1Enciende Lo Bueno!\",\"publisher\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-GT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization\",\"name\":\"Guatevision\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-GT\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png\",\"contentUrl\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png\",\"width\":1000,\"height\":600,\"caption\":\"Guatevision\"},\"image\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal de delitos electorales deja el cargo temporalmente","description":"El fiscal encargado de investigar casos como financiamiento electoral de partidos pol\u00edticos estar\u00e1 fuera de labores hasta septiembre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo","og_locale":"es_ES","og_type":"article","og_title":"Fiscal de delitos electorales deja el cargo temporalmente","og_description":"El fiscal encargado de investigar casos como financiamiento electoral de partidos pol\u00edticos estar\u00e1 fuera de labores hasta septiembre.","og_url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo","og_site_name":"Guatevision","article_modified_time":"2019-06-14T01:02:42+00:00","og_image":[{"width":760,"height":430,"url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/oscar-schaad-.jpg?quality=82","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo","name":"Fiscal de delitos electorales deja el cargo temporalmente","isPartOf":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo#primaryimage"},"image":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo#primaryimage"},"thumbnailUrl":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/oscar-schaad-.jpg","datePublished":"2019-06-09T03:14:43+00:00","dateModified":"2019-06-14T01:02:42+00:00","description":"El fiscal encargado de investigar casos como financiamiento electoral de partidos pol\u00edticos estar\u00e1 fuera de labores hasta septiembre.","inLanguage":"es-GT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo"]}]},{"@type":"ImageObject","inLanguage":"es-GT","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/noticias\/nacional\/fiscal-delitos-electorales-cargo#primaryimage","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/oscar-schaad-.jpg","contentUrl":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2019\/06\/oscar-schaad-.jpg","width":760,"height":430,"caption":"Oscar Schaad, fiscal delitos electorales"},{"@type":"WebSite","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/","name":"Guatevision","description":"\u00a1Enciende Lo Bueno!","publisher":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-GT"},{"@type":"Organization","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization","name":"Guatevision","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/","logo":{"@type":"ImageObject","inLanguage":"es-GT","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png","contentUrl":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png","width":1000,"height":600,"caption":"Guatevision"},"image":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/post-noticias\/279318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/post-noticias"}],"about":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/types\/post-noticias"}],"author":[{"embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/users\/104"}],"version-history":[{"count":0,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/post-noticias\/279318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/media\/279336"}],"wp:attachment":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/media?parent=279318"}],"wp:term":[{"taxonomy":"etiqueta","embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/etiqueta?post=279318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}