{"id":476629,"date":"2022-04-15T11:02:41","date_gmt":"2022-04-15T17:02:41","guid":{"rendered":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/?p=476629"},"modified":"2022-04-15T11:02:41","modified_gmt":"2022-04-15T17:02:41","slug":"por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona","status":"publish","type":"post","link":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona","title":{"rendered":"Marlene Rodr\u00edguez, mam\u00e1 de Evaluna: &#8220;Siento que es perfecto volver a la \u00e9poca de las comadronas&#8221;"},"content":{"rendered":"<p>El nacimiento de <strong>\u00cdndigo Echeverry Reglero<\/strong> ha sido una de las noticias m\u00e1s interesantes a seguir durante el \u00faltimo a\u00f1o tanto para seguidores de los artistas <strong>Evaluna<\/strong> y <strong>Camilo<\/strong>, as\u00ed como del cantante <strong>Ricardo Montaner<\/strong> -padre de Evaluna-.<\/p>\n\n<p>Una de las cosas que m\u00e1s llam\u00f3 la atenci\u00f3n durante los meses de embarazo de Evaluna fue el hecho que ni ella ni el cantante de &#8220;Millones&#8221; quer\u00edan saber <strong>cu\u00e1l era el g\u00e9nero<\/strong> de su hijo o hija, <strong>hasta que naciera.<\/strong><\/p>\n<p>Pero la espera y las dudas fueron resueltas con el nacimiento el pasado <strong>6 de abril del 2022<\/strong>. Ese d\u00eda la familia anunci\u00f3 en redes sociales que se trataba de una ni\u00f1a.<\/p>\n<p>Otro de los temas que rode\u00f3 el proceso tuvo que ver con <strong>la labor de parto<\/strong> elegida por la dupla. Seg\u00fan dijo Ricardo Montaner al programa Ventaneando, el nacimiento de \u00cdndigo <strong>estaba planeado para realizarse a trav\u00e9s de una partera.<\/strong><\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CcJD4JgrWrq\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Ver esta publicaci\u00f3n en Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CcJD4JgrWrq\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de C A M I L O (@camilo)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>&#8220;Va a nacer de forma muy natural. Probablemente en agua, lo van a decidir en el momento&#8221;, <a href=\"https:\/\/peopleenespanol.com\/mamas-y-bebes\/se-revelan-detalles-nacimiento-bebe-de-eva-luna-y-camilo\/\">dijo el cantante<\/a> a inicios de abril de 2022.<\/p>\n<p>Tambi\u00e9n se dio a conocer que <strong>Marlene Rodr\u00edguez<\/strong> -madre de Evaluna y esposa de Montaner- estar\u00eda muy de cerca en el recibimiento de \u00cdndigo. De esa cuenta que se hab\u00eda dedicado a aprender como ser &#8216;doula&#8217; o asistente de partos.<\/p>\n<p>De acuerdo con el portal <a href=\"https:\/\/peopleenespanol.com\/mamas-y-bebes\/evaluna-madre-participara-en-parto-se-capacito-como-partera\/\">People en Espa\u00f1ol<\/a>, Rodr\u00edguez hab\u00eda asegurado un a\u00f1o antes a Book Corner: &#8220;[Me] capacit\u00e9 justamente porque quer\u00eda saber <strong>a profundidad lo que eso significaba<\/strong> y la verdad es que una cosa me fue llevando a la otra y la verdad es que lo disfrut\u00e9 un mont\u00f3n porque siento que es perfecto volver a la \u00e9poca de las <strong>comadronas<\/strong>&#8220;.<\/p>\n<p>Cabe resaltar que en ese entonces la madre de Evaluna hab\u00eda estado de cerca al embarazo, pero <strong>no confirm\u00f3 que iba a ayudar directamente a su hija en la labor de parto<\/strong>. &#8220;No [me capacit\u00e9] porque voy a ser [la doula de mi hija], porque me da mucho nervio. Pero amo eso&#8221;, asegur\u00f3 Rodr\u00edguez.<\/p>\n<p>El inter\u00e9s de la esposa de Ricardo Montaner a prop\u00f3sito del nacimiento de su nieta tambi\u00e9n la hab\u00eda llevado a escribir en 2021 <em>Evaluna Creciente<\/em>, un libro que dedic\u00f3 al <strong>proceso de gestaci\u00f3n<\/strong> de su hija, como el de otras mujeres.<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CK2FjVIgMop\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Ver esta publicaci\u00f3n en Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/CK2FjVIgMop\/?utm_source=ig_embed&amp;utm_campaign=loading\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida de Marlene Rodriguez M. Montaner (@marlenesalome)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Evaluna Creciente aborda &#8220;los mitos, las costumbres, lo que es mejor evitar, lo que debe incorporar, <strong>lo que me hubiera gustado saber cuando tuve a mis hijos<\/strong>. Un libro de amor y por amor&#8230;a ella, a mis hijas nuevas y a las que se unan&#8221;, comparti\u00f3 Marlene en su cuenta de Instagram.<\/p>\n<p>Adem\u00e1s del libro que public\u00f3 en 2021, Rodr\u00edguez tambi\u00e9n inici\u00f3 un <strong>emprendimiento de ropa para menores<\/strong>, seg\u00fan afirm\u00f3 Ricardo Montaner a la revista People en Espa\u00f1ol. &#8220;Marlene acaba de crear una l\u00ednea de ropa para beb\u00e9s, inspirada en \u00cdndigo. Est\u00e1 muy entusiasmada y, obviamente, Eva Luna&#8221;, habr\u00eda dicho el cantante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marlene Rodriguez M. Montaner asegur\u00f3 que se hab\u00eda capacitado para ser &#8216;doula&#8217; debido a su inter\u00e9s en el proceso de dar a luz. <\/p>\n","protected":false},"author":234,"featured_media":476634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[39736],"etiqueta":[41171,50343,50342,50344],"class_list":["post-476629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculo","etiqueta-camilo","etiqueta-eva-luna","etiqueta-indigo","etiqueta-partera"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marlene Rodr\u00edguez, mam\u00e1 de Evaluna: &quot;Siento que es perfecto volver a la \u00e9poca de las comadronas&quot; - Guatevision<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marlene Rodr\u00edguez, mam\u00e1 de Evaluna: &quot;Siento que es perfecto volver a la \u00e9poca de las comadronas&quot; - Guatevision\" \/>\n<meta property=\"og:description\" content=\"Marlene Rodriguez M. Montaner asegur\u00f3 que se hab\u00eda capacitado para ser &#039;doula&#039; debido a su inter\u00e9s en el proceso de dar a luz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona\" \/>\n<meta property=\"og:site_name\" content=\"Guatevision\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-15T17:02:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg?quality=82\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alejandro Ortiz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jortiz\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alejandro Ortiz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona#article\",\"isPartOf\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona\"},\"author\":{\"name\":\"Alejandro Ortiz\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/person\/bdd963dab9a7d23bbe93ed882d70b92e\"},\"headline\":\"Marlene Rodr\u00edguez, mam\u00e1 de Evaluna: &#8220;Siento que es perfecto volver a la \u00e9poca de las comadronas&#8221;\",\"datePublished\":\"2022-04-15T17:02:41+00:00\",\"dateModified\":\"2022-04-15T17:02:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona\"},\"wordCount\":564,\"publisher\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization\"},\"image\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg\",\"articleSection\":[\"Espect\u00e1culos\"],\"inLanguage\":\"es-GT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona\",\"name\":\"Marlene Rodr\u00edguez, mam\u00e1 de Evaluna: \\\"Siento que es perfecto volver a la \u00e9poca de las comadronas\\\" - Guatevision\",\"isPartOf\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona#primaryimage\"},\"image\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona#primaryimage\"},\"thumbnailUrl\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg\",\"datePublished\":\"2022-04-15T17:02:41+00:00\",\"dateModified\":\"2022-04-15T17:02:41+00:00\",\"inLanguage\":\"es-GT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-GT\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona#primaryimage\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg\",\"contentUrl\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg\",\"width\":1200,\"height\":746,\"caption\":\"Antes del nacimiento de \u00cdndigo, la madre de la cantante Evaluna se capacit\u00f3 para ser comadrona\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/\",\"name\":\"Guatevision\",\"description\":\"\u00a1Enciende Lo Bueno!\",\"publisher\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-GT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization\",\"name\":\"Guatevision\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-GT\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png\",\"contentUrl\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png\",\"width\":1000,\"height\":600,\"caption\":\"Guatevision\"},\"image\":{\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/person\/bdd963dab9a7d23bbe93ed882d70b92e\",\"name\":\"Alejandro Ortiz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-GT\",\"@id\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/person\/image\/40277045025679b594a41c070407c488\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fb435face0d4743b70315d4e2fad3e2f426109c5af5e962117e287f14f586d4b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fb435face0d4743b70315d4e2fad3e2f426109c5af5e962117e287f14f586d4b?s=96&d=mm&r=g\",\"caption\":\"Alejandro Ortiz\"},\"sameAs\":[\"https:\/\/x.com\/jortiz\"],\"url\":\"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/author\/jortiz\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marlene Rodr\u00edguez, mam\u00e1 de Evaluna: \"Siento que es perfecto volver a la \u00e9poca de las comadronas\" - Guatevision","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona","og_locale":"es_ES","og_type":"article","og_title":"Marlene Rodr\u00edguez, mam\u00e1 de Evaluna: \"Siento que es perfecto volver a la \u00e9poca de las comadronas\" - Guatevision","og_description":"Marlene Rodriguez M. Montaner asegur\u00f3 que se hab\u00eda capacitado para ser 'doula' debido a su inter\u00e9s en el proceso de dar a luz.","og_url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona","og_site_name":"Guatevision","article_published_time":"2022-04-15T17:02:41+00:00","og_image":[{"width":1200,"height":746,"url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg?quality=82","type":"image\/jpeg"}],"author":"Alejandro Ortiz","twitter_card":"summary_large_image","twitter_creator":"@jortiz","twitter_misc":{"Written by":"Alejandro Ortiz","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona#article","isPartOf":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona"},"author":{"name":"Alejandro Ortiz","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/person\/bdd963dab9a7d23bbe93ed882d70b92e"},"headline":"Marlene Rodr\u00edguez, mam\u00e1 de Evaluna: &#8220;Siento que es perfecto volver a la \u00e9poca de las comadronas&#8221;","datePublished":"2022-04-15T17:02:41+00:00","dateModified":"2022-04-15T17:02:41+00:00","mainEntityOfPage":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona"},"wordCount":564,"publisher":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization"},"image":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona#primaryimage"},"thumbnailUrl":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg","articleSection":["Espect\u00e1culos"],"inLanguage":"es-GT"},{"@type":"WebPage","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona","name":"Marlene Rodr\u00edguez, mam\u00e1 de Evaluna: \"Siento que es perfecto volver a la \u00e9poca de las comadronas\" - Guatevision","isPartOf":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona#primaryimage"},"image":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona#primaryimage"},"thumbnailUrl":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg","datePublished":"2022-04-15T17:02:41+00:00","dateModified":"2022-04-15T17:02:41+00:00","inLanguage":"es-GT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona"]}]},{"@type":"ImageObject","inLanguage":"es-GT","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/espectaculo\/por-esta-razon-la-mama-de-evaluna-quiso-aprender-a-ser-comadrona#primaryimage","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg","contentUrl":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg","width":1200,"height":746,"caption":"Antes del nacimiento de \u00cdndigo, la madre de la cantante Evaluna se capacit\u00f3 para ser comadrona"},{"@type":"WebSite","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#website","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/","name":"Guatevision","description":"\u00a1Enciende Lo Bueno!","publisher":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-GT"},{"@type":"Organization","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#organization","name":"Guatevision","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/","logo":{"@type":"ImageObject","inLanguage":"es-GT","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/","url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png","contentUrl":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2026\/04\/Diseno-sin-titulo.png","width":1000,"height":600,"caption":"Guatevision"},"image":{"@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/person\/bdd963dab9a7d23bbe93ed882d70b92e","name":"Alejandro Ortiz","image":{"@type":"ImageObject","inLanguage":"es-GT","@id":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/#\/schema\/person\/image\/40277045025679b594a41c070407c488","url":"https:\/\/secure.gravatar.com\/avatar\/fb435face0d4743b70315d4e2fad3e2f426109c5af5e962117e287f14f586d4b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb435face0d4743b70315d4e2fad3e2f426109c5af5e962117e287f14f586d4b?s=96&d=mm&r=g","caption":"Alejandro Ortiz"},"sameAs":["https:\/\/x.com\/jortiz"],"url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/author\/jortiz"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-content\/uploads\/sites\/2\/2022\/04\/6GUU3G5B4NGILIOZ7CBNGKL5OU.jpg","_links":{"self":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/posts\/476629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/users\/234"}],"replies":[{"embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/comments?post=476629"}],"version-history":[{"count":0,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/posts\/476629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/media\/476634"}],"wp:attachment":[{"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/media?parent=476629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/categories?post=476629"},{"taxonomy":"etiqueta","embeddable":true,"href":"https:\/\/prensalibre-com-develop.go-vip.co\/guatevision\/wp-json\/wp\/v2\/etiqueta?post=476629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}